{"id":72733,"date":"2026-03-16T19:12:28","date_gmt":"2026-03-16T23:12:28","guid":{"rendered":"https:\/\/us.harlequinfloors.com\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/"},"modified":"2026-05-12T12:06:24","modified_gmt":"2026-05-12T16:06:24","slug":"harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone","status":"publish","type":"post","link":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/","title":{"rendered":"Harlequin devient le partenaire officiel des rev\u00eatements de sol d&rsquo;Ovation by DanceOne"},"content":{"rendered":"\n<p>Harlequin est fier d&rsquo;annoncer son partenariat avec <a href=\"https:\/\/ovationdancetour.com\/\" type=\"link\" id=\"https:\/\/ovationdancetour.com\/\">Ovation by DanceOne<\/a> en tant que <strong>partenaire officiel des planchers<\/strong> pour l&rsquo;exp\u00e9rience r\u00e9volutionnaire de danse de salon et de danse latine de l&rsquo;organisation.<\/p>\n\n<p>Gr\u00e2ce \u00e0 ce partenariat, les \u00e9v\u00e9nements de danse de salon d&rsquo;Ovation seront \u00e9quip\u00e9s d&rsquo;un plancher de danse professionnel Harlequin, offrant aux danseurs une surface de performance con\u00e7ue sp\u00e9cifiquement pour les exigences de l&rsquo;entra\u00eenement, de la comp\u00e9tition et de la performance de haut niveau. Le plancher de danse Harlequin Liberty Ballroom est une version personnalis\u00e9e du syst\u00e8me de panneaux de suspension <a href=\"https:\/\/us.harlequinfloors.com\/fr\/floors\/harlequin-liberty-latchloc\/\" type=\"link\" id=\"https:\/\/us.harlequinfloors.com\/en\/floors\/harlequin-liberty-latchloc\/\">Harlequin Liberty LatchLoc\u00ae<\/a>, dot\u00e9 d&rsquo;une surface imprim\u00e9e imitant les planchers \u00e0 l&rsquo;aspect bois auxquels les danseurs de danse de salon et de danse latine sont habitu\u00e9s.   <\/p>\n\n<p>Les danseurs et les organisations du monde entier font confiance aux planchers Harlequin pour leur qualit\u00e9, leur durabilit\u00e9 et leur s\u00e9curit\u00e9. Con\u00e7us pour offrir une sensation id\u00e9ale sous les pieds avec un juste \u00e9quilibre entre r\u00e9sistance au glissement et absorption des chocs, les planchers Harlequin aident \u00e0 soutenir la performance des danseurs tout en r\u00e9duisant le risque de blessure. <\/p>\n\n<p>Ovation fait partie de <strong><a href=\"https:\/\/dance.one\/\" type=\"link\" id=\"https:\/\/dance.one\/\">DanceOne<\/a><\/strong>la plus grande famille de marques de danse au monde. Fond\u00e9e en 2023 et bas\u00e9e \u00e0 Los Angeles, DanceOne rassemble certaines des conventions, des comp\u00e9titions et des exp\u00e9riences \u00e9ducatives les plus respect\u00e9es de l&rsquo;industrie dans le cadre d&rsquo;une vision commune : faire progresser l&rsquo;enseignement de la danse tout en pr\u00e9servant l&rsquo;art et l&rsquo;int\u00e9grit\u00e9 de la forme d&rsquo;art. <\/p>\n\n<p>En 2024, DanceOne s&rsquo;est associ\u00e9 aux c\u00e9l\u00e8bres danseurs et chor\u00e9graphes <strong>Julianne et Derek Hough<\/strong> pour lancer Ovation, un \u00e9v\u00e9nement dynamique de danse de salon et de danse latine qui combine les meilleurs \u00e9l\u00e9ments de l&rsquo;entra\u00eenement conventionnel et de la danse de comp\u00e9tition. L&rsquo;exp\u00e9rience offre une instruction de classe mondiale, des opportunit\u00e9s de comp\u00e9tition et des plateformes de performance con\u00e7ues pour inspirer et \u00e9lever la prochaine g\u00e9n\u00e9ration de danseurs. <\/p>\n\n<p>Harlequin est honor\u00e9 de soutenir Ovation et DanceOne dans leur mission de favoriser des exp\u00e9riences de danse s\u00fbres, inspirantes et de haute qualit\u00e9 pour la communaut\u00e9 mondiale de la danse.<\/p>\n\n<p>Le programme complet de la tourn\u00e9e Ovation est disponible \u00e0 l&rsquo;adresse <a href=\"https:\/\/ovationdancetour.com\/tour-dates\/\">suivante : https:\/\/ovationdancetour.com\/tour-dates\/.<\/a><\/p>\n\n<p><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Harlequin est fier d&rsquo;annoncer son partenariat avec Ovation by DanceOne en tant que partenaire officiel des planchers pour l&rsquo;exp\u00e9rience r\u00e9volutionnaire&#8230;<\/p>\n<p><a class=\"btn btn-primary btn-an harlequin-read-more-link\" href=\"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/\">En savoir plus<\/a><\/p>\n","protected":false},"author":5792,"featured_media":72009,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[552],"tags":[1295,497,441,442,1296,1294],"class_list":["post-72733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements","tag-danceone","tag-flooring-fr","tag-harlequin-fr","tag-harlequin-floors-fr","tag-libertylatchloc","tag-ovation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Harlequin devient le partenaire officiel des rev\u00eatements de sol d&#039;Ovation by DanceOne | Harlequin Floors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Harlequin devient le partenaire officiel des rev\u00eatements de sol d&#039;Ovation by DanceOne\" \/>\n<meta property=\"og:description\" content=\"Harlequin est fier d&rsquo;annoncer son partenariat avec Ovation by DanceOne en tant que partenaire officiel des planchers pour l&rsquo;exp\u00e9rience r\u00e9volutionnaire...En savoir plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/\" \/>\n<meta property=\"og:site_name\" content=\"Harlequin Floors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/americanharlequinfloors\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-16T23:12:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T16:06:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/us.harlequinfloors.com\/wp-content\/uploads\/2026\/03\/Meet-N-Greet_Chicago-Ovation-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aimee Ruiz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aimee Ruiz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/\"},\"author\":{\"name\":\"Aimee Ruiz\",\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/#\\\/schema\\\/person\\\/da7b88bef967d3e9f03a652412461db6\"},\"headline\":\"Harlequin devient le partenaire officiel des rev\u00eatements de sol d&rsquo;Ovation by DanceOne\",\"datePublished\":\"2026-03-16T23:12:28+00:00\",\"dateModified\":\"2026-05-12T16:06:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/\"},\"wordCount\":416,\"image\":{\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/us.harlequinfloors.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Meet-N-Greet_Chicago-Ovation-scaled.jpeg\",\"keywords\":[\"danceone\",\"flooring\",\"harlequin\",\"harlequin floors\",\"libertylatchloc\",\"ovation\"],\"articleSection\":[\"\u00c9v\u00e9nements\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/\",\"url\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/\",\"name\":\"Harlequin devient le partenaire officiel des rev\u00eatements de sol d'Ovation by DanceOne | Harlequin Floors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/us.harlequinfloors.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Meet-N-Greet_Chicago-Ovation-scaled.jpeg\",\"datePublished\":\"2026-03-16T23:12:28+00:00\",\"dateModified\":\"2026-05-12T16:06:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/#\\\/schema\\\/person\\\/da7b88bef967d3e9f03a652412461db6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/us.harlequinfloors.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Meet-N-Greet_Chicago-Ovation-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/us.harlequinfloors.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Meet-N-Greet_Chicago-Ovation-scaled.jpeg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Harlequin devient le partenaire officiel des rev\u00eatements de sol d&#8217;Ovation by DanceOne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/\",\"name\":\"Harlequin Floors\",\"description\":\"The World Dances sur les planchers et tapis de danse Harlequin Floors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/us.harlequinfloors.com\\\/fr\\\/#\\\/schema\\\/person\\\/da7b88bef967d3e9f03a652412461db6\",\"name\":\"Aimee Ruiz\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Harlequin devient le partenaire officiel des rev\u00eatements de sol d'Ovation by DanceOne | Harlequin Floors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/","og_locale":"fr_FR","og_type":"article","og_title":"Harlequin devient le partenaire officiel des rev\u00eatements de sol d'Ovation by DanceOne","og_description":"Harlequin est fier d&rsquo;annoncer son partenariat avec Ovation by DanceOne en tant que partenaire officiel des planchers pour l&rsquo;exp\u00e9rience r\u00e9volutionnaire...En savoir plus","og_url":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/","og_site_name":"Harlequin Floors","article_publisher":"https:\/\/www.facebook.com\/americanharlequinfloors","article_published_time":"2026-03-16T23:12:28+00:00","article_modified_time":"2026-05-12T16:06:24+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/us.harlequinfloors.com\/wp-content\/uploads\/2026\/03\/Meet-N-Greet_Chicago-Ovation-scaled.jpeg","type":"image\/jpeg"}],"author":"Aimee Ruiz","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Aimee Ruiz","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/#article","isPartOf":{"@id":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/"},"author":{"name":"Aimee Ruiz","@id":"https:\/\/us.harlequinfloors.com\/fr\/#\/schema\/person\/da7b88bef967d3e9f03a652412461db6"},"headline":"Harlequin devient le partenaire officiel des rev\u00eatements de sol d&rsquo;Ovation by DanceOne","datePublished":"2026-03-16T23:12:28+00:00","dateModified":"2026-05-12T16:06:24+00:00","mainEntityOfPage":{"@id":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/"},"wordCount":416,"image":{"@id":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/#primaryimage"},"thumbnailUrl":"https:\/\/us.harlequinfloors.com\/wp-content\/uploads\/2026\/03\/Meet-N-Greet_Chicago-Ovation-scaled.jpeg","keywords":["danceone","flooring","harlequin","harlequin floors","libertylatchloc","ovation"],"articleSection":["\u00c9v\u00e9nements"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/","url":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/","name":"Harlequin devient le partenaire officiel des rev\u00eatements de sol d'Ovation by DanceOne | Harlequin Floors","isPartOf":{"@id":"https:\/\/us.harlequinfloors.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/#primaryimage"},"image":{"@id":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/#primaryimage"},"thumbnailUrl":"https:\/\/us.harlequinfloors.com\/wp-content\/uploads\/2026\/03\/Meet-N-Greet_Chicago-Ovation-scaled.jpeg","datePublished":"2026-03-16T23:12:28+00:00","dateModified":"2026-05-12T16:06:24+00:00","author":{"@id":"https:\/\/us.harlequinfloors.com\/fr\/#\/schema\/person\/da7b88bef967d3e9f03a652412461db6"},"breadcrumb":{"@id":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/#primaryimage","url":"https:\/\/us.harlequinfloors.com\/wp-content\/uploads\/2026\/03\/Meet-N-Greet_Chicago-Ovation-scaled.jpeg","contentUrl":"https:\/\/us.harlequinfloors.com\/wp-content\/uploads\/2026\/03\/Meet-N-Greet_Chicago-Ovation-scaled.jpeg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/us.harlequinfloors.com\/fr\/harlequin-devient-le-partenaire-officiel-des-revetements-de-sol-dovation-by-danceone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/us.harlequinfloors.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Harlequin devient le partenaire officiel des rev\u00eatements de sol d&#8217;Ovation by DanceOne"}]},{"@type":"WebSite","@id":"https:\/\/us.harlequinfloors.com\/fr\/#website","url":"https:\/\/us.harlequinfloors.com\/fr\/","name":"Harlequin Floors","description":"The World Dances sur les planchers et tapis de danse Harlequin Floors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/us.harlequinfloors.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/us.harlequinfloors.com\/fr\/#\/schema\/person\/da7b88bef967d3e9f03a652412461db6","name":"Aimee Ruiz"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:31:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/us.harlequinfloors.com\/fr\/wp-json\/wp\/v2\/posts\/72733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/us.harlequinfloors.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/us.harlequinfloors.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/us.harlequinfloors.com\/fr\/wp-json\/wp\/v2\/users\/5792"}],"replies":[{"embeddable":true,"href":"https:\/\/us.harlequinfloors.com\/fr\/wp-json\/wp\/v2\/comments?post=72733"}],"version-history":[{"count":1,"href":"https:\/\/us.harlequinfloors.com\/fr\/wp-json\/wp\/v2\/posts\/72733\/revisions"}],"predecessor-version":[{"id":72736,"href":"https:\/\/us.harlequinfloors.com\/fr\/wp-json\/wp\/v2\/posts\/72733\/revisions\/72736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/us.harlequinfloors.com\/fr\/wp-json\/wp\/v2\/media\/72009"}],"wp:attachment":[{"href":"https:\/\/us.harlequinfloors.com\/fr\/wp-json\/wp\/v2\/media?parent=72733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/us.harlequinfloors.com\/fr\/wp-json\/wp\/v2\/categories?post=72733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/us.harlequinfloors.com\/fr\/wp-json\/wp\/v2\/tags?post=72733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}